{"id":1007,"date":"2013-02-20T00:27:05","date_gmt":"2013-02-19T15:27:05","guid":{"rendered":"https:\/\/staging.gengo.com\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages-2\/"},"modified":"2014-06-14T02:38:50","modified_gmt":"2014-06-13T17:38:50","slug":"google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages","status":"publish","type":"news","link":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/","title":{"rendered":"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube"},"content":{"rendered":"<p>Hoy Google <a href=\"http:\/\/youtubecreator.blogspot.ca\/2013\/02\/get-your-youtube-video-captions.html\">ha agregado<\/a> funciones nuevas al Administrador de video de YouTube: proveedores de traducci\u00f3n que ofrecen a cualquier usuario acceso a traductores profesionales para crear subt\u00edtulos r\u00e1pidos en 36 idiomas distintos.<\/p>\r\n<p>El servicio de intercambio de videos implement\u00f3 <a href=\"http:\/\/youtubecreator.blogspot.co.uk\/2012\/09\/build-global-audience-on-youtube-by.html\">en setiembre del a\u00f1o pasado<\/a> el bot\u00f3n Solicitar traducci\u00f3n, que proporciona a los propietarios de canal una forma f\u00e1cil de crear documentos de subt\u00edtulos para traducci\u00f3n y compartirlos con otras personas.<\/p>\r\n<p>No obstante, no todo el mundo tiene acceso a muchos amigos que sepan hablar varios idiomas. Para solucionar este problema, Google se ha asociado con dos empresas, <a href=\"\/\">Gengo<\/a> y <a href=\"http:\/\/www.translated.net\/en\/\">Translated.net<\/a>, para ofrecer traducciones profesionales y acelerar todo el proceso en YouTube.<\/p>\r\n<p>Una vez que los usuarios hagan clic en Solicitar traducci\u00f3n, ver\u00e1n a los dos proveedores con informaci\u00f3n relevante, incluidos los m\u00e9todos de pago aceptados, el precio aproximado y la fecha de finalizaci\u00f3n.<\/p>\r\n<p>A continuaci\u00f3n, se dirigir\u00e1 a los propietarios del canal al sitio web del proveedor para completar el pago. Despu\u00e9s de completar la traducci\u00f3n, se la volver\u00e1 a enviar a YouTube, donde el usuario podr\u00e1 aprobar los nuevos subt\u00edtulos y aprobarlos para que se publiquen.<\/p>\r\n<p>La nueva funci\u00f3n har\u00e1 que sea m\u00e1s f\u00e1cil para todos (desde vloggers independientes hasta difusores a gran escala o empresas multimedia) cargar contenido en una gran variedad de idiomas. Esto es una mejora, aunque se puede esperar que algunos usuarios no est\u00e9n dispuestos a pagar por los servicios de una empresa de traducci\u00f3n profesional.<\/p>\r\n<p>La noticia de hoy es un corolario al anuncio <a href=\"http:\/\/thenextweb.com\/insider\/2013\/02\/06\/amara-launches-a-free-version-of-its-crowdsourced-subtitling-platform-for-youtube-users\/?fromcat=all\">este mes<\/a> de que Amara, una plataforma de subt\u00edtulos mediante crowsdsourcing, ha lanzado una versi\u00f3n gratuita de su servicio para usuarios de YouTube.<\/p>\r\n<p><a href=\"http:\/\/thenextweb.com\/insider\/2013\/02\/20\/youtube-partners-with-gengo-and-translated-net-to-offer-users-professional-captioning-in-more-than-300-\r\nlanguages\/\">Lea el art\u00edculo original en TNW<\/a><\/p>","protected":false},"excerpt":{"rendered":"Hoy Google ha agregado funciones nuevas al Administrador de video de YouTube: proveedores de traducci\u00f3n que ofrecen a cualquier usuario acceso a traductores profesionales para crear subt\u00edtulos r\u00e1pidos en 36 idiomas distintos. El servicio de intercambio de videos implement\u00f3 en setiembre del a\u00f1o pasado el bot\u00f3n Solicitar traducci\u00f3n, que proporciona a los propietarios de canal [&hellip;]","protected":false},"author":2,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1007","news","type-news","status-publish","hentry","press-coverage-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo\" \/>\n<meta property=\"og:description\" content=\"Hoy Google ha agregado funciones nuevas al Administrador de video de YouTube: proveedores de traducci\u00f3n que ofrecen a cualquier usuario acceso a traductores profesionales para crear subt\u00edtulos r\u00e1pidos en 36 idiomas distintos. El servicio de intercambio de videos implement\u00f3 en setiembre del a\u00f1o pasado el bot\u00f3n Solicitar traducci\u00f3n, que proporciona a los propietarios de canal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/\" \/>\n<meta property=\"og:site_name\" content=\"Gengo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mygengo\" \/>\n<meta property=\"article:modified_time\" content=\"2014-06-13T17:38:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gengoit\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\\\/\",\"url\":\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\\\/\",\"name\":\"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#website\"},\"datePublished\":\"2013-02-19T15:27:05+00:00\",\"dateModified\":\"2014-06-13T17:38:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gengo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/gengo.com\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gengo.com\\\/es\\\/\",\"name\":\"Gengo\",\"description\":\"Translation Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gengo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#organization\",\"name\":\"Gengo\",\"url\":\"https:\\\/\\\/gengo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gengo.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/gengo_favicon.png\",\"contentUrl\":\"https:\\\/\\\/gengo.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/gengo_favicon.png\",\"width\":260,\"height\":260,\"caption\":\"Gengo\"},\"image\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mygengo\",\"https:\\\/\\\/x.com\\\/gengoit\",\"https:\\\/\\\/www.instagram.com\\\/gengoit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gengo\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/gengo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/","og_locale":"es_ES","og_type":"article","og_title":"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo","og_description":"Hoy Google ha agregado funciones nuevas al Administrador de video de YouTube: proveedores de traducci\u00f3n que ofrecen a cualquier usuario acceso a traductores profesionales para crear subt\u00edtulos r\u00e1pidos en 36 idiomas distintos. El servicio de intercambio de videos implement\u00f3 en setiembre del a\u00f1o pasado el bot\u00f3n Solicitar traducci\u00f3n, que proporciona a los propietarios de canal [&hellip;]","og_url":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/","og_site_name":"Gengo","article_publisher":"https:\/\/www.facebook.com\/mygengo","article_modified_time":"2014-06-13T17:38:50+00:00","twitter_card":"summary_large_image","twitter_site":"@gengoit","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/","url":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/","name":"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube - Gengo","isPartOf":{"@id":"https:\/\/gengo.com\/es\/#website"},"datePublished":"2013-02-19T15:27:05+00:00","dateModified":"2014-06-13T17:38:50+00:00","breadcrumb":{"@id":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gengo.com\/es\/news\/google-partners-with-gengo-and-translated-net-for-professional-youtube-captioning-in-36-languages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gengo.com\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/gengo.com\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Google se asocia con Gengo y Translated.net para ofrecer subt\u00edtulos profesionales en 36 idiomas en YouTube"}]},{"@type":"WebSite","@id":"https:\/\/gengo.com\/es\/#website","url":"https:\/\/gengo.com\/es\/","name":"Gengo","description":"Translation Service","publisher":{"@id":"https:\/\/gengo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gengo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gengo.com\/es\/#organization","name":"Gengo","url":"https:\/\/gengo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gengo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gengo.com\/wp-content\/uploads\/2019\/06\/gengo_favicon.png","contentUrl":"https:\/\/gengo.com\/wp-content\/uploads\/2019\/06\/gengo_favicon.png","width":260,"height":260,"caption":"Gengo"},"image":{"@id":"https:\/\/gengo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mygengo","https:\/\/x.com\/gengoit","https:\/\/www.instagram.com\/gengoit\/","https:\/\/www.linkedin.com\/company\/gengo\/","https:\/\/www.youtube.com\/user\/gengo"]}]}},"_links":{"self":[{"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/news\/1007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/comments?post=1007"}],"version-history":[{"count":0,"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/news\/1007\/revisions"}],"wp:attachment":[{"href":"https:\/\/gengo.com\/es\/wp-json\/wp\/v2\/media?parent=1007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}