{"id":84925,"date":"2021-08-04T13:56:14","date_gmt":"2021-08-04T04:56:14","guid":{"rendered":"https:\/\/staging.gengo.com\/?post_type=resource&#038;p=84925"},"modified":"2021-08-04T15:50:52","modified_gmt":"2021-08-04T06:50:52","slug":"most-common-mistakes-en-2","status":"publish","type":"resource","link":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/","title":{"rendered":"Most common mistakes: English"},"content":{"rendered":"<h2><b>Erreurs fr\u00e9quentes en fran\u00e7ais canadien<\/b><\/h2>\r\n<p><span style=\"font-weight: 400;\">Le fran\u00e7ais canadien comporte certaines particularit\u00e9s qui le diff\u00e9rencie du fran\u00e7ais de France. Ce document a \u00e9t\u00e9 con\u00e7u afin de vous aider \u00e0 rep\u00e9rer et \u00e0 \u00e9viter certaines des erreurs les plus fr\u00e9quentes en fran\u00e7ais canadien.<\/span><\/p>\r\n<p><b>Anglicismes et termes erron\u00e9s\u00a0<\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Ces erreurs surviennent surtout lorsqu\u2019un terme est traduit litt\u00e9ralement en fran\u00e7ais canadien ou lorsqu\u2019un terme anglais est conserv\u00e9 en anglais alors qu\u2019il existe un terme plus appropri\u00e9 en fran\u00e7ais canadien.<\/span><\/p>\r\n<p><b><i>Exemples :<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : I sent him an email.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Je lui ai envoy\u00e9 un mail. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 Je lui ai envoy\u00e9 un courriel. <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : We organized a meeting to discuss smartphone use.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Nous avons organis\u00e9 un meeting pour discuter de l\u2019utilisation des smartphones. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Nous avons organis\u00e9 une r\u00e9union pour discuter de l\u2019utilisation des t\u00e9l\u00e9phones intelligents. <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : Reparations for Indigenous peoples.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : R\u00e9parations pour les peuples indig\u00e8nes. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 R\u00e9parations pour les peuples autochtones. <\/span><span style=\"font-weight: 400;\">\u2714<\/span> <span style=\"font-weight: 400;\"><br \/>\r\n<\/span><\/p>\r\n<p><b><i>Comment \u00e9viter ces erreurs?<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">M\u00e9fiez-vous des anglicismes. Le fran\u00e7ais canadien cr\u00e9e souvent de nouveaux mots ou propose des traductions plut\u00f4t que d\u2019utiliser des mots anglais qui sont tol\u00e9r\u00e9s en France. Par exemple, des mots comme \u00ab business \u00bb,\u00a0 \u00ab meeting \u00bb et \u00ab sponsoring \u00bb sont utilis\u00e9s en France, alors que \u00ab affaires \u00bb, \u00ab r\u00e9union \u00bb et \u00ab commanditaires \u00bb sont pr\u00e9f\u00e9r\u00e9s au Canada.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Veuillez consulter les ressources linguistiques fournies par le gouvernement f\u00e9d\u00e9ral (par exemple, <\/span><a href=\"https:\/\/www.btb.termiumplus.gc.ca\/tpv2alpha\/alpha-fra.html?lang=fra&amp;index=alt\"><span style=\"font-weight: 400;\">TERMIUM Plus\u00ae<\/span><\/a><span style=\"font-weight: 400;\">) et le gouvernement provincial (par exemple, <\/span><a href=\"http:\/\/gdt.oqlf.gouv.qc.ca\/\"><span style=\"font-weight: 400;\">Le grand dictionnaire terminologique<\/span><\/a><span style=\"font-weight: 400;\">) pour trouver le mot juste.<\/span><\/p>\r\n<p><b>Faux amis et traductions litt\u00e9rales<\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Ces erreurs surviennent lorsqu\u2019un mot, une expression ou une partie de la phrase est traduite litt\u00e9ralement en fran\u00e7ais canadien. En particulier, un faux ami est un mot en fran\u00e7ais dont le sens est parfois confondu avec celui d\u2019un mot en anglais.\u00a0<\/span><\/p>\r\n<p><b><i>Exemples :<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : I support this cause.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Je supporte cette cause. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 J\u2019encourage cette cause. <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : Definitely! She is positive this is a great idea.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : D\u00e9finitivement! Elle est positive que c\u2019est une bonne id\u00e9e. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Sans aucun doute! Elle est certaine\/s\u00fbre que c\u2019est une bonne id\u00e9e. <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : Alternatively, we\u2019ll be addressing the question.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Alternativement, nous adresserons la question. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Sinon, nous nous attaquerons \u00e0 la question. <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><b><i>Comment \u00e9viter ces erreurs?<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Votre phrase se rapproche-t-elle trop de l\u2019anglais? Prenez soin de bien relire votre texte afin de vous assurer que vous n\u2019empruntez pas involontairement un terme de l\u2019anglais. <\/span><a href=\"https:\/\/www.noslangues-ourlanguages.gc.ca\/fr\/dictionnaire-des-cooccurrences\/index-fra\"><span style=\"font-weight: 400;\">Le dictionnaire des cooccurrences<\/span><\/a><span style=\"font-weight: 400;\"> est un outil pr\u00e9cieux qui propose une liste d\u2019adjectifs et de verbes s\u2019employant avec certains noms communs.\u00a0<\/span><\/p>\r\n<p><b>Erreurs de syntaxe<\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Une erreur de syntaxe survient lorsqu\u2019une phrase enti\u00e8re ou une grande partie de celle-ci ne se lit pas bien. C\u2019est souvent le cas lorsqu\u2019une phrase conserve sa structure anglaise lorsqu\u2019elle est traduite en fran\u00e7ais : on parle ici de calques syntaxiques.\u00a0<\/span><\/p>\r\n<p><b><i>Exemples :<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : If I am vaccinated but cannot locate my card, what should I do?\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : <\/span><span style=\"font-weight: 400;\">Si je suis vaccin\u00e9 mais que je ne trouve pas ma carte, qu\u2019est-ce que je dois faire? <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Je suis vaccin\u00e9, mais je ne trouve pas ma carte. Que dois-je faire? <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : Outside of mask wearing and social distancing, what do you suggest?<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Le port du masque et de la distanciation sociale \u00e0 part, qu\u2019est-ce que vous sugg\u00e9rez? <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Outre le port du masque et la distanciation sociale, que sugg\u00e9rez-vous? <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : for example without limitation<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : par exemple sans limitation <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 par exemple, sans toutefois s\u2019y limiter <\/span><span style=\"font-weight: 400;\">\u2714<\/span> <span style=\"font-weight: 400;\"><br \/>\r\n<\/span><\/p>\r\n<p><b><i>Comment \u00e9viter ces erreurs?<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Assurez-vous que votre traduction se lit bien. N\u2019h\u00e9sitez pas \u00e0 reformuler une phrase dans vos propres mots ou \u00e0 la scinder. Vous pouvez \u00e9galement consulter des sites tels que <\/span><a href=\"https:\/\/www.wordreference.com\/enfr\/\"><span style=\"font-weight: 400;\">WordReference<\/span><\/a><span style=\"font-weight: 400;\"> ou <\/span><a href=\"https:\/\/www.linguee.com\/\"><span style=\"font-weight: 400;\">Linguee.com<\/span><\/a><span style=\"font-weight: 400;\"> pour voir comment d\u2019autres gens ont traduit des phrases semblables. Veillez \u00e0 ce que les exemples proviennent de sources reconnues, et pr\u00e9f\u00e9rablement de sources canadiennes, surtout lorsque vous utilisez Linguee. Les sources canadiennes sont facilement rep\u00e9rables gr\u00e2ce au code pays \u00ab .ca \u00bb ou au code provincial \u00ab .qc.ca \u00bb.<\/span><\/p>\r\n<p><b>Erreurs d\u2019orthographe<\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Ces erreurs surviennent surtout lorsque les accents ou les majuscules sont mal utilis\u00e9s, ou lorsque les chiffres en dessous de 10 ne sont pas \u00e9crits en lettres. Aussi, les mots form\u00e9s avec les pr\u00e9fixes \u00ab auto \u00bb, \u00ab anti \u00bb\u00a0et autres s\u2019\u00e9crivent habituellement sans trait d\u2019union.<\/span><\/p>\r\n<p><b><i>Exemples :<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : 7 Things To Do This Summer<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : 7 Activit\u00e9s A Faire Cet Et\u00e9 <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 Sept activit\u00e9s \u00e0 faire cet \u00e9t\u00e9 <\/span><span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : Selfie #7639<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : Auto-portrait #7639 <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA : Autoportrait <\/span><span style=\"font-weight: 400;\">n\u00ba 7639<\/span> <span style=\"font-weight: 400;\">\u2714<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">EN : I\u2019ll be on time in the future.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">FR-CA : A l\u2019avenir, je serai \u00e0 l\u2019heure. <\/span><span style=\"font-weight: 400;\">\u2716<\/span><span style=\"font-weight: 400;\"><br \/>\r\n<\/span><span style=\"font-weight: 400;\">FR-CA :\u00a0 \u00c0 l\u2019avenir, je serai \u00e0 l\u2019heure. <\/span><span style=\"font-weight: 400;\">\u2714<\/span> <span style=\"font-weight: 400;\"><br \/>\r\n<\/span><\/p>\r\n<p><b><i>Comment \u00e9viter ces erreurs?<\/i><\/b><\/p>\r\n<p><span style=\"font-weight: 400;\">Le correcteur automatique ne d\u00e9tectera pas les erreurs d\u2019accentuation (par exemple, \u00ab tache \u00bb au lieu de \u00ab t\u00e2che \u00bb). Veuillez accorder une attention particuli\u00e8re aux mots accentu\u00e9s.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Notez que les lettres majuscules doivent \u00eatre accentu\u00e9es (par exemple, \u00ab \u00c9prouvez-vous de la joie? \u00bb et non \u00ab Eprouvez-vous de la joie? \u00bb).\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">M\u00e9fiez-vous des majuscules superflues. Les mois et les jours de l\u2019ann\u00e9e ne prennent pas de majuscules, de m\u00eame que les nationalit\u00e9s et les langues, sauf s\u2019il s\u2019agit de noms propres. Les titres de poste devant un nom propre ne prennent pas la majuscule (par exemple, \u00ab la directrice Martine Beaubien \u00bb et non \u00ab la Directrice Martine Beaubien \u00bb).\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Pour l&#8217;emploi du trait d\u2019union<\/span><span style=\"font-weight: 400;\">, veuillez vous r\u00e9f\u00e9rer \u00e0 la ressource suivante : <\/span><a href=\"http:\/\/bdl.oqlf.gouv.qc.ca\/bdl\/gabarit_bdl.asp?Th=1&amp;Th_id=162\"><span style=\"font-weight: 400;\">Mots compos\u00e9s avec pr\u00e9fixe ou \u00e9l\u00e9ment grec ou latin<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>","protected":false},"excerpt":{"rendered":"Erreurs fr\u00e9quentes en fran\u00e7ais canadien Le fran\u00e7ais canadien comporte certaines particularit\u00e9s qui le diff\u00e9rencie du fran\u00e7ais de France. Ce document a \u00e9t\u00e9 con\u00e7u afin de vous aider \u00e0 rep\u00e9rer et \u00e0 \u00e9viter certaines des erreurs les plus fr\u00e9quentes en fran\u00e7ais canadien. Anglicismes et termes erron\u00e9s\u00a0 Ces erreurs surviennent surtout lorsqu\u2019un terme est traduit litt\u00e9ralement en [&hellip;]","protected":false},"author":45,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-84925","resource","type-resource","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Most common mistakes: English - Gengo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Most common mistakes: English - Gengo\" \/>\n<meta property=\"og:description\" content=\"Erreurs fr\u00e9quentes en fran\u00e7ais canadien Le fran\u00e7ais canadien comporte certaines particularit\u00e9s qui le diff\u00e9rencie du fran\u00e7ais de France. Ce document a \u00e9t\u00e9 con\u00e7u afin de vous aider \u00e0 rep\u00e9rer et \u00e0 \u00e9viter certaines des erreurs les plus fr\u00e9quentes en fran\u00e7ais canadien. Anglicismes et termes erron\u00e9s\u00a0 Ces erreurs surviennent surtout lorsqu\u2019un terme est traduit litt\u00e9ralement en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Gengo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mygengo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T06:50:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gengoit\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/translators\\\/resources\\\/most-common-mistakes-en-2\\\/\",\"url\":\"https:\\\/\\\/gengo.com\\\/fr\\\/translators\\\/resources\\\/most-common-mistakes-en-2\\\/\",\"name\":\"Most common mistakes: English - Gengo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-08-04T04:56:14+00:00\",\"dateModified\":\"2021-08-04T06:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/translators\\\/resources\\\/most-common-mistakes-en-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gengo.com\\\/fr\\\/translators\\\/resources\\\/most-common-mistakes-en-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/translators\\\/resources\\\/most-common-mistakes-en-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gengo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Most common mistakes: English\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gengo.com\\\/fr\\\/\",\"name\":\"Gengo\",\"description\":\"Translation Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gengo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#organization\",\"name\":\"Gengo\",\"url\":\"https:\\\/\\\/gengo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gengo.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/gengo_favicon.png\",\"contentUrl\":\"https:\\\/\\\/gengo.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/gengo_favicon.png\",\"width\":260,\"height\":260,\"caption\":\"Gengo\"},\"image\":{\"@id\":\"https:\\\/\\\/gengo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mygengo\",\"https:\\\/\\\/x.com\\\/gengoit\",\"https:\\\/\\\/www.instagram.com\\\/gengoit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gengo\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/gengo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Most common mistakes: English - Gengo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Most common mistakes: English - Gengo","og_description":"Erreurs fr\u00e9quentes en fran\u00e7ais canadien Le fran\u00e7ais canadien comporte certaines particularit\u00e9s qui le diff\u00e9rencie du fran\u00e7ais de France. Ce document a \u00e9t\u00e9 con\u00e7u afin de vous aider \u00e0 rep\u00e9rer et \u00e0 \u00e9viter certaines des erreurs les plus fr\u00e9quentes en fran\u00e7ais canadien. Anglicismes et termes erron\u00e9s\u00a0 Ces erreurs surviennent surtout lorsqu\u2019un terme est traduit litt\u00e9ralement en [&hellip;]","og_url":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/","og_site_name":"Gengo","article_publisher":"https:\/\/www.facebook.com\/mygengo","article_modified_time":"2021-08-04T06:50:52+00:00","twitter_card":"summary_large_image","twitter_site":"@gengoit","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/","url":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/","name":"Most common mistakes: English - Gengo","isPartOf":{"@id":"https:\/\/gengo.com\/fr\/#website"},"datePublished":"2021-08-04T04:56:14+00:00","dateModified":"2021-08-04T06:50:52+00:00","breadcrumb":{"@id":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gengo.com\/fr\/translators\/resources\/most-common-mistakes-en-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gengo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Most common mistakes: English"}]},{"@type":"WebSite","@id":"https:\/\/gengo.com\/fr\/#website","url":"https:\/\/gengo.com\/fr\/","name":"Gengo","description":"Translation Service","publisher":{"@id":"https:\/\/gengo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gengo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gengo.com\/fr\/#organization","name":"Gengo","url":"https:\/\/gengo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gengo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/gengo.com\/wp-content\/uploads\/2019\/06\/gengo_favicon.png","contentUrl":"https:\/\/gengo.com\/wp-content\/uploads\/2019\/06\/gengo_favicon.png","width":260,"height":260,"caption":"Gengo"},"image":{"@id":"https:\/\/gengo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mygengo","https:\/\/x.com\/gengoit","https:\/\/www.instagram.com\/gengoit\/","https:\/\/www.linkedin.com\/company\/gengo\/","https:\/\/www.youtube.com\/user\/gengo"]}]}},"_links":{"self":[{"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/resource\/84925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/types\/resource"}],"author":[{"embeddable":true,"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/comments?post=84925"}],"version-history":[{"count":0,"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/resource\/84925\/revisions"}],"wp:attachment":[{"href":"https:\/\/gengo.com\/fr\/wp-json\/wp\/v2\/media?parent=84925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}